{"id":1103,"date":"2017-11-29T09:00:00","date_gmt":"2017-11-29T09:00:00","guid":{"rendered":"https:\/\/ferpam.widehomolog.biz\/blog\/?p=1103"},"modified":"2021-09-22T14:34:51","modified_gmt":"2021-09-22T14:34:51","slug":"mais-uma-loja-ferpam","status":"publish","type":"post","link":"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/","title":{"rendered":"Mais uma loja FERPAM"},"content":{"rendered":"<p>Somos a Ferpam e estamos no mercado tocantinense desde 1996. Ao todo, s\u00e3o mais de duas d\u00e9cadas de pioneirismo, compromisso e carinho por nossos clientes e colaboradores. Desde que inauguramos, n\u00e3o paramos de crescer no segmento de Ferramentas, Parafusos e M\u00e1quinas.<\/p>\n<p>Temos por miss\u00e3o oferecer mais alta qualidade para nossos clientes, raz\u00e3o pela qual, temos investido na busca de novas tecnologias para facilitar sua vida e o seu trabalho.<\/p>\n<p>Sucesso no Tocantins, atendemos a capital Palmas com duas lojas, sendo Ferpam Matriz e Borrachas Confian\u00e7a, especializada em mangueiras, irriga\u00e7\u00e3o, hidr\u00e1ulica e Energia Solar. Al\u00e9m disso, temos uma filial em Gurupi e outra em Aragua\u00edna (Ferpam Borrachas).<\/p>\n<p>Atendemos tamb\u00e9m em todo o Brasil, dispondo de uma linha completa com mais de 25 mil tipos de produtos, dentre: ferramentas, parafusos, m\u00e1quinas, equipamentos de prote\u00e7\u00e3o e assist\u00eancia t\u00e9cnica certificada.<\/p>\n<h3>Produtos Relacionados<\/h3><div class=\"tie-row wide-mage\"><\/div>  <script>\r\n                        jQuery(document).ready(function(){\r\n                            jQuery('.wide-mage').slick({\r\n                                infinite: true,\r\n                                slidesToShow: 3,\r\n                                slidesToScroll: 3,\r\n                                responsive: [\r\n                                    {\r\n                                      breakpoint: 480,\r\n                                      settings: {\r\n                                        slidesToShow: 2,\r\n                                        slidesToScroll: 2\r\n                                      }\r\n                                    }\r\n                                ]\r\n                            });\r\n                            var highestBox = 37;\r\n        \r\n                        \r\n                            jQuery('.wide-mage .title').each(function(){\r\n                                \r\n                                if(jQuery(this).height() > highestBox) {\r\n                                    highestBox = jQuery(this).height(); \r\n                                }\r\n                            \r\n                            });  \r\n                                    \r\n                            \r\n                            jQuery('.wide-mage .title').height(highestBox);\r\n                                            \r\n                        }); \r\n                    <\/script>\n","protected":false},"excerpt":{"rendered":"<p>Somos a Ferpam e estamos no mercado tocantinense desde 1996. Ao todo, s\u00e3o mais de duas d\u00e9cadas de pioneirismo, compromisso e carinho por nossos clientes e colaboradores. Desde que inauguramos, n\u00e3o paramos de crescer no segmento de Ferramentas, Parafusos e M\u00e1quinas. Temos por miss\u00e3o oferecer mais alta qualidade para nossos clientes, raz\u00e3o pela qual, temos &hellip;<\/p>\n","protected":false},"author":13,"featured_media":1107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[646,645,644,787,788],"class_list":["post-1103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-ferpam","tag-https-www-ferpam-com-br","tag-historia-ferpam","tag-melhor-loja-de-ferramentas","tag-obra","tag-planeje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mais uma loja FERPAM - Blog Ferpam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais uma loja FERPAM - Blog Ferpam\" \/>\n<meta property=\"og:description\" content=\"Somos a Ferpam e estamos no mercado tocantinense desde 1996. Ao todo, s\u00e3o mais de duas d\u00e9cadas de pioneirismo, compromisso e carinho por nossos clientes e colaboradores. Desde que inauguramos, n\u00e3o paramos de crescer no segmento de Ferramentas, Parafusos e M\u00e1quinas. Temos por miss\u00e3o oferecer mais alta qualidade para nossos clientes, raz\u00e3o pela qual, temos &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ferpam\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-29T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-22T14:34:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ferpam.com.br\/blog\/wp-content\/uploads\/2017\/11\/24a653d0ce8342a2e4eea678965e977f.png\" \/>\n\t<meta property=\"og:image:width\" content=\"381\" \/>\n\t<meta property=\"og:image:height\" content=\"229\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"1 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#organization\",\"name\":\"Ferpam\",\"url\":\"https:\/\/www.ferpam.com.br\/blog\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.ferpam.com.br\/blog\/wp-content\/uploads\/2021\/02\/logo-1.png\",\"width\":254,\"height\":89,\"caption\":\"Ferpam\"},\"image\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#website\",\"url\":\"https:\/\/www.ferpam.com.br\/blog\/\",\"name\":\"Blog Ferpam\",\"description\":\"Not\\u00edcias da Ferpam\",\"publisher\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.ferpam.com.br\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.ferpam.com.br\/blog\/wp-content\/uploads\/2017\/11\/24a653d0ce8342a2e4eea678965e977f.png\",\"width\":381,\"height\":229},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#webpage\",\"url\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/\",\"name\":\"Mais uma loja FERPAM - Blog Ferpam\",\"isPartOf\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#primaryimage\"},\"datePublished\":\"2017-11-29T09:00:00+00:00\",\"dateModified\":\"2021-09-22T14:34:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/\",\"url\":\"https:\/\/www.ferpam.com.br\/blog\/\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/\",\"url\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/\",\"name\":\"Mais uma loja FERPAM\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#\/schema\/person\/051564fd045ecd71f1aded8d56d18790\"},\"headline\":\"Mais uma loja FERPAM\",\"datePublished\":\"2017-11-29T09:00:00+00:00\",\"dateModified\":\"2021-09-22T14:34:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#webpage\"},\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#primaryimage\"},\"keywords\":\"Ferpam,hist\\u00f3ria ferpam,melhor loja de ferramentas,obra,planeje\",\"articleSection\":\"Not\\u00edcias Ferpam\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ferpam.com.br\/blog\/mais-uma-loja-ferpam\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#\/schema\/person\/051564fd045ecd71f1aded8d56d18790\",\"name\":\"Ferpam\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ferpam.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/92d7aed1da9197829cbb554cc586347e69b47f94274092b05a685ca0b0e5f192?s=96&d=mm&r=g\",\"caption\":\"Ferpam\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/posts\/1103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1103"}],"version-history":[{"count":14,"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/posts\/1103\/revisions"}],"predecessor-version":[{"id":2304,"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/posts\/1103\/revisions\/2304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/media\/1107"}],"wp:attachment":[{"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ferpam.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}